{"id":6584,"date":"2021-10-06T09:29:59","date_gmt":"2021-10-06T07:29:59","guid":{"rendered":"https:\/\/agencement.gravor.com\/?p=6584"},"modified":"2023-04-24T09:35:09","modified_gmt":"2023-04-24T07:35:09","slug":"gamme-originelle-gravor-2","status":"publish","type":"post","link":"https:\/\/www.gravor.com\/en\/gamme-originelle-gravor-2\/","title":{"rendered":"Notre nouveaut\u00e9 2021 : gamme \u00ab\u00a0originelle\u00a0\u00bb"},"content":{"rendered":"<h2 class=\"wp-block-heading has-text-align-center\" data-block-type=\"core\"><meta charset=\"utf-8\">Grav&rsquo;Or propose un nouveau savoir-faire \u00e0 base de mati\u00e8re naturelle, des oeuvres faites \u00e0 partir de sucre d&rsquo;\u00e9rable, de terre naturelle ou encore d&rsquo;\u00e9pices<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\" data-block-type=\"core\"><img decoding=\"async\" src=\"https:\/\/agencement.gravor.com\/wp-content\/uploads\/2021\/09\/unnamed2-1024x768.jpeg\" alt=\"Salon architect@work 2021 gamme originelle\" class=\"wp-image-6571\" title=\"\"><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" data-block-type=\"core\">La fusion de la terre et du verre<\/h3>\n\n\n\n<p data-block-type=\"core\">Tout commence en janvier 2020 lors de notre s\u00e9lection \u00e0 l\u2019\u00c9lys\u00e9e pour l\u2019\u00e9v\u00e9nement du <a href=\"https:\/\/www.elysee.fr\/emmanuel-macron\/la-grande-exposition-du-fabrique-en-france#publication-list\" target=\"_blank\" rel=\"noreferrer noopener\">\u00ab savoir-faire made in France \u00bb<\/a>. L&rsquo;exposition met \u00e0 l&rsquo;honneur les produits de 120 entreprises, chacune repr\u00e9sentante d&rsquo;un d\u00e9partement fran\u00e7ais. Grav\u2019Or a eu le plaisir d\u2019exposer son \u0153uvre \u00ab <a href=\"https:\/\/boutique.gravor.com\/produit\/elysee-02\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00c9lys\u00e9e<\/a> \u00bb pour repr\u00e9senter le territoire Sarthois. Une \u0153uvre alliant verre laqu\u00e9 en \u00e9glomis\u00e9, gravure \u00e0 la main et feuille d\u2019or.<\/p>\n\n\n\n<p data-block-type=\"core\">Lors de ce bel \u00e9v\u00e9nement, l\u2019entreprise fait la rencontre d\u2019un exposant venant d\u2019Ardennes avec un savoir-faire atypique : la fabrique de terres colorantes naturelles. Cette rencontre va inspirer l\u2019entreprise \u00e0 cr\u00e9er des \u0153uvres alliant la terre et le verre.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\" data-block-type=\"core\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/agencement.gravor.com\/wp-content\/uploads\/2021\/09\/DSC_2307-1024x683.jpg\" alt=\"gamme originelle\" class=\"wp-image-6585 size-full\" title=\"\"><\/figure><div class=\"wp-block-media-text__content\">\n<p data-block-type=\"core\">C\u2019est donc en mars 2020 que les premiers essais sont effectu\u00e9s. Malheureusement le confinement vient bousculer cette innovation, et ce n\u2019est qu\u2019en juin 2020 que les tests officiels commencent. Un nouveau savoir-faire se cr\u00e9e alors, la fusion entre le verre et la terre donne l\u2019effet escompt\u00e9 et c\u2019est avec le temps que de nouvelles techniques naturelles viennent compl\u00e9ter la gamme originelle.<\/p>\n\n\n\n<p data-block-type=\"core\">Les \u00e9pices et le sucre s\u2019ajoutent donc \u00e0 ce beau savoir-faire, qui aujourd\u2019hui ne cesse d\u2019\u00e9voluer gr\u00e2ce \u00e0 de nouvelles techniques et fa\u00e7ons de travailler la mati\u00e8re naturelle.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\" data-block-type=\"core\"><div class=\"wp-block-media-text__content\">\n<p data-block-type=\"core\">La gamme \u00ab originelle \u00bb voit le jour pour la premi\u00e8re fois dans un projet de luxe : la seconde boutique de Marc-Antoine Barrois \u00e0 Paris.<br>Un chantier alliant la vision du couturier et le savoir-faire Grav\u2019Or.<\/p>\n\n\n\n<p data-block-type=\"core\">Les murs en verre de la boutique sont faits \u00e0 partir de sucre d\u2019\u00e9rable. Ils cr\u00e9ent un c\u00f4t\u00e9 nuageux et apportent une touche de l\u00e9g\u00e8ret\u00e9 \u00e0 l\u2019espace. Les diff\u00e9rents ombrages et contrastes color\u00e9s viennent quant \u00e0 eux donner du caract\u00e8re et une touche exclusive au lieu.<\/p>\n\n\n\n<p data-block-type=\"core\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" data-block-type=\"core\">Alors curieux ? <\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" data-block-type=\"core\">D\u00e9couvrez notre <a href=\"https:\/\/agencement.gravor.com\/materiautheque\/\" target=\"_blank\" rel=\"noreferrer noopener\">gamme \u00ab\u00a0originelle\u00a0\u00bb<\/a><\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\" data-block-type=\"core\">\n<div class=\"wp-block-button\" data-block-type=\"core\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/architecture.gravor.com\/materiautheque\/\" target=\"_blank\" rel=\"noreferrer noopener\">D\u00e9couvrir<\/a><\/div>\n<\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/agencement.gravor.com\/wp-content\/uploads\/2021\/09\/CP-NOUVELLE-BOUTIQUE-MARC-ANTOINE-BARROIS-PARFUMS5-e1626624606117-1.jpg\" alt=\"boutique Marc-Antoine Barrois\" class=\"wp-image-6587 size-full\" title=\"\"><\/figure><\/div>","protected":false},"excerpt":{"rendered":"<p>Grav&rsquo;Or propose un nouveau savoir-faire \u00e0 base de mati\u00e8re naturelle, des oeuvres faites \u00e0 partir de sucre d&rsquo;\u00e9rable, de terre naturelle ou encore d&rsquo;\u00e9pices La fusion de la terre et du verre Tout commence en janvier 2020 lors de notre s\u00e9lection \u00e0 l\u2019\u00c9lys\u00e9e pour l\u2019\u00e9v\u00e9nement du \u00ab savoir-faire made in France \u00bb. L&rsquo;exposition met \u00e0 [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":7948,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-6584","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/www.gravor.com\/en\/wp-json\/wp\/v2\/posts\/6584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gravor.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gravor.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gravor.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gravor.com\/en\/wp-json\/wp\/v2\/comments?post=6584"}],"version-history":[{"count":0,"href":"https:\/\/www.gravor.com\/en\/wp-json\/wp\/v2\/posts\/6584\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gravor.com\/en\/wp-json\/wp\/v2\/media\/7948"}],"wp:attachment":[{"href":"https:\/\/www.gravor.com\/en\/wp-json\/wp\/v2\/media?parent=6584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gravor.com\/en\/wp-json\/wp\/v2\/categories?post=6584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gravor.com\/en\/wp-json\/wp\/v2\/tags?post=6584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}